{"id":1592,"date":"2009-11-16T08:09:16","date_gmt":"2009-11-16T07:09:16","guid":{"rendered":"http:\/\/www.scriptopolis.fr\/?p=1592"},"modified":"2012-12-13T17:10:37","modified_gmt":"2012-12-13T16:10:37","slug":"entites-episode-2-reservations","status":"publish","type":"post","link":"https:\/\/www.scriptopolis.fr\/en\/entites-episode-2-reservations\/","title":{"rendered":"Entit\u00e9s, \u00e9pisode 2. R\u00e9servations"},"content":{"rendered":"<p><a href=\"http:\/\/www.scriptopolis.fr\/wp-content\/uploads\/2012\/12\/entites2.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.scriptopolis.fr\/wp-content\/uploads\/2012\/12\/entites2.jpg\" alt=\"\" title=\"entites2\" width=\"400\" height=\"400\" class=\"alignnone size-full wp-image-1593\" srcset=\"https:\/\/www.scriptopolis.fr\/wp-content\/uploads\/2012\/12\/entites2.jpg 400w, https:\/\/www.scriptopolis.fr\/wp-content\/uploads\/2012\/12\/entites2-150x150.jpg 150w, https:\/\/www.scriptopolis.fr\/wp-content\/uploads\/2012\/12\/entites2-300x300.jpg 300w, https:\/\/www.scriptopolis.fr\/wp-content\/uploads\/2012\/12\/entites2-305x305.jpg 305w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Kortrijk. Ao\u00fbt 2009.<\/p>\n<p>Dans un espace ouvert, la fabrique de seuils est diff\u00e9rente. La configuration architecturale ne consiste pas en un lieu que l\u2019on traverse de l\u2019int\u00e9rieur. En ville, un parking de supermarch\u00e9 est g\u00e9n\u00e9ralement d\u00e9limit\u00e9 par une zone goudronn\u00e9e et des b\u00e2timents qui le jouxtent. La circulation y est beaucoup plus libre. Outre les v\u00e9hiculent dot\u00e9s d\u2019un moteur, d\u2019autres entit\u00e9s y sont accept\u00e9es. Les humains, m\u00eame \u00e9quip\u00e9s de rollers ou d\u2019un v\u00e9lo, sont bienvenus. Les animaux aussi. Au fil du temps, certaines plantes peuvent m\u00eame s\u2019y installer durablement, sans faire partie du d\u00e9cor initial.<br \/>\nLe seuil de d\u00e9part est tr\u00e8s bas, l\u2019acc\u00e8s tr\u00e8s peu restreint. Dans un espace tr\u00e8s largement ouvert \u00e0 la circulation, l\u2019enjeu est donc de produire une r\u00e9servation. Pour cela, un panneau avec quelques mots ne suffit souvent pas. \u00c0 certaines heures de la journ\u00e9e, la comp\u00e9tition pour les meilleurs places du parking, les plus proches de l\u2019entr\u00e9e du supermarch\u00e9, fait rage. Outre un panneau, un marquage au sol \u00e0 la peinture qui d\u00e9limite des emplacements sp\u00e9cifiques est parfois n\u00e9cessaire pour fabriquer un seuil. L\u2019ajout d\u2019une ic\u00f4ne au milieu de l\u2019espace circonscrit peut venir sp\u00e9cifier davantage encore la r\u00e9servation. Pour occuper de telles places, il ne suffit pas d\u2019\u00eatre un humain. Au contraire, il faut \u00eatre \u00e9quip\u00e9 d\u2019une certaine proth\u00e8se : un humain-en-fauteuil-roulant ou un humain-avec-une-poussette-pour-enfants.<br \/>\nQuelques traits de peinture au sol se transforment ainsi en un v\u00e9ritable geste moral. Ils pr\u00e9cisent l\u2019\u00e9tendue du caract\u00e8re public de cet espace. Ils sp\u00e9cifient jusqu\u2019\u00e0 quel point ce dernier accepte l\u2019expression des diff\u00e9rences. Tout espace dit public est cens\u00e9 faire une place \u00e0 chacun, pour son confort physique et moral. Au risque de flirter avec une stigmatisation qui, parce qu\u2019elle est durablement inscrite dans le sol, oppose \u00e0 l\u2019inattention civile (si bien d\u00e9crite par Erving Goffman) une obligation de pr\u00eater attention \u00e0 celles et ceux que d\u00e9signe ce qui est \u00e9crit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kortrijk. Ao\u00fbt 2009. Dans un espace ouvert, la fabrique de seuils est diff\u00e9rente. La configuration architecturale ne consiste pas en un lieu que l\u2019on traverse de l\u2019int\u00e9rieur. En ville, un parking de supermarch\u00e9 est g\u00e9n\u00e9ralement d\u00e9limit\u00e9 par une zone goudronn\u00e9e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1593,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"footnotes":"","activitypub_content_warning":"","activitypub_content_visibility":""},"categories":[12,14],"tags":[],"jetpack_featured_media_url":"https:\/\/www.scriptopolis.fr\/wp-content\/uploads\/2012\/12\/entites2.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pDxzW-pG","_links":{"self":[{"href":"https:\/\/www.scriptopolis.fr\/en\/wp-json\/wp\/v2\/posts\/1592"}],"collection":[{"href":"https:\/\/www.scriptopolis.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.scriptopolis.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.scriptopolis.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scriptopolis.fr\/en\/wp-json\/wp\/v2\/comments?post=1592"}],"version-history":[{"count":1,"href":"https:\/\/www.scriptopolis.fr\/en\/wp-json\/wp\/v2\/posts\/1592\/revisions"}],"predecessor-version":[{"id":1594,"href":"https:\/\/www.scriptopolis.fr\/en\/wp-json\/wp\/v2\/posts\/1592\/revisions\/1594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scriptopolis.fr\/en\/wp-json\/wp\/v2\/media\/1593"}],"wp:attachment":[{"href":"https:\/\/www.scriptopolis.fr\/en\/wp-json\/wp\/v2\/media?parent=1592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.scriptopolis.fr\/en\/wp-json\/wp\/v2\/categories?post=1592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.scriptopolis.fr\/en\/wp-json\/wp\/v2\/tags?post=1592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}